{"id":2345,"date":"2018-08-11T12:25:17","date_gmt":"2018-08-11T16:25:17","guid":{"rendered":"https:\/\/2018-fr.montreal.wordcamp.org\/?p=2345"},"modified":"2018-08-12T09:33:43","modified_gmt":"2018-08-12T13:33:43","slug":"hover","status":"publish","type":"post","link":"https:\/\/montreal.wordcamp.org\/2018-fr\/hover\/","title":{"rendered":"[Contenu Commandit\u00e9] Hover \u2013 Avez-vous trouv\u00e9 le bon nom de domaine ?"},"content":{"rendered":"<p>Nous sommes vraiment heureux de vous rencontrer !<\/p>\n<p>L\u2019\u00e9quipe de Hover se r\u00e9jouit se joindre \u00e0 la Communaut\u00e9 au WordCamp Montreal 2018, et ne peut pas \u00eatre plus impatient ! Nous sommes chanceux d\u2019\u00eatre entour\u00e9 d\u2019une communaut\u00e9 aussi large et cr\u00e9ative de personnes passionn\u00e9es. Mais plus important, nous avons h\u00e2te de d\u00e9couvrir vos histoires personnelles derri\u00e8re vos cr\u00e9ations WordPress !<\/p>\n<h2><strong>\u00c0 propos de Hover<\/strong><\/h2>\n<p>Hover offre un service d\u2019enregistrement de nom de domaine. Notre mission est simple \u2013 pour permettre l\u2019expression de votre passion, nous fournissons un acc\u00e8s aux meilleurs noms de domaine et au meilleur support client. Que vous soyez passionn\u00e9 de cuisine ou la prochaine start-up qui changera le monde, notre \u00e9quipe est l\u00e0 pour vous aider \u00e0 b\u00e2tir votre identit\u00e9 en ligne.<\/p>\n<p>G\u00e9rez tous vos noms de domaine en une seule place, gr\u00e2ce au panneau de contr\u00f4le. La fonctionnalit\u00e9 \u00ab\u00a0Hover Connect\u00a0\u00bb vous permet de connecter facilement votre nom de domaine \u00e0 plusieurs plateformes. Si vous avez besoin d\u2019aide, notre incroyable \u00e9quipe de support sera l\u00e0 pour vous guider.<\/p>\n<p>Notre \u00e9quipe irait sur la lune pour vous aider \u00e0 faire vivre votre passion. Vous avez un nom de domaine ailleurs et souhaitez le transf\u00e9rer chez Hover ? Ne vous inqui\u00e9tez pas, notre service gratuit \u00ab\u00a0Valet Transfer\u00a0\u00bb est fait pour \u00e7a !<\/p>\n<h2><strong>Hover et la Communaut\u00e9, une longue histoire d\u2019amiti\u00e9 !<\/strong><\/h2>\n<p>Profitez de notre sp\u00e9cial du moment ! Nous offrons actuellement l\u2019extension <strong>.CLUB<\/strong> \u00e0 -65% ! Accueillez vos visiteurs comme des membres <a href=\"https:\/\/www.hover.com\/tld\/buy-club-domain\">pour 4.99$.<\/a><\/p>\n<p>Quelqu\u2019un un jour a dit que tout est une question de choix. Chez Hover, nous pensons que vous trouverez le parfait nom de domaine pour votre activit\u00e9 !<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Nous avons h\u00e2te d\u2019\u00e9couter votre histoire ! <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes vraiment heureux de vous rencontrer ! L\u2019\u00e9quipe de Hover se r\u00e9jouit se joindre \u00e0 la Communaut\u00e9 au WordCamp Montreal 2018, et ne peut pas \u00eatre plus impatient ! Nous sommes chanceux d\u2019\u00eatre entour\u00e9 d\u2019une communaut\u00e9 aussi large et cr\u00e9ative de personnes passionn\u00e9es. Mais plus important, nous avons h\u00e2te de d\u00e9couvrir vos histoires personnelles &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/montreal.wordcamp.org\/2018-fr\/hover\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;[Contenu Commandit\u00e9] Hover \u2013 Avez-vous trouv\u00e9 le bon nom de domaine ?&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":16224074,"featured_media":2346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1256287],"tags":[],"class_list":["post-2345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-commanditaire"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/sheMNR-hover","jetpack_featured_media_url":"https:\/\/montreal.wordcamp.org\/2018-fr\/files\/2018\/08\/Hover_photo.png","_links":{"self":[{"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/posts\/2345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/users\/16224074"}],"replies":[{"embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/comments?post=2345"}],"version-history":[{"count":1,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/posts\/2345\/revisions"}],"predecessor-version":[{"id":2347,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/posts\/2345\/revisions\/2347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/media\/2346"}],"wp:attachment":[{"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/media?parent=2345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/categories?post=2345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2018-fr\/wp-json\/wp\/v2\/tags?post=2345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}