{"id":2767,"date":"2019-07-09T23:31:16","date_gmt":"2019-07-09T23:31:16","guid":{"rendered":"http:\/\/2019-fr.montreal.wordcamp.org\/?post_type=wcb_sponsor&#038;p=2767"},"modified":"2019-07-09T23:31:17","modified_gmt":"2019-07-09T23:31:17","slug":"hebergement-web-canada","status":"publish","type":"wcb_sponsor","link":"https:\/\/montreal.wordcamp.org\/2019-fr\/sponsor\/hebergement-web-canada\/","title":{"rendered":"H\u00e9bergement Web Canada"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/whc.ca\/\" rel=\"nofollow\">H\u00e9bergement Web Canada<\/a> (WHC) est une soci\u00e9t\u00e9 de technologie bas\u00e9e \u00e0 Montr\u00e9al. Nous sommes une \u00e9quipe de professionnels du web, travaillant ensemble pour aider les petites entreprises canadiennes \u00e0 s\u2019\u00e9tablir et \u00e0 r\u00e9ussir en ligne. Avec plus de 30 000 clients actifs, WHC est l\u2019une des entreprises web avec la plus forte croissance au Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ann\u00e9e derni\u00e8re, nous annoncions le lancement de l\u2019<a href=\"https:\/\/whc.ca\/hebergement-wordpress\/\" rel=\"nofollow\">H\u00e9bergement WordPress<\/a>, une solution parmi les plus rapides et abordables au Canada. Cet \u00e9t\u00e9, nous faisons \u00e9voluer ce service davantage, avec un nouveau syst\u00e8me de staging pour d\u00e9ployer vos changements rapidement et en toute s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de l\u2019h\u00e9bergement WordPress, H\u00e9bergement Web Canada propose:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Un <a href=\"https:\/\/whc.ca\/hebergement-sites-web\" rel=\"nofollow\">H\u00e9bergement Web<\/a> optimis\u00e9, h\u00e9berg\u00e9 \u00e0 100% au Canada<\/li><li>Des <a href=\"https:\/\/whc.ca\/serveurs-cloud-canadiens\" rel=\"nofollow\">serveurs Cloud infog\u00e9r\u00e9s<\/a> avec cPanel et un acc\u00e8s root complet<\/li><li><a href=\"https:\/\/whc.ca\/serveurs-dedies\" rel=\"nofollow\">Serveurs D\u00e9di\u00e9s<\/a> pour un contr\u00f4le in\u00e9gal\u00e9<\/li><li>Plus de 400 extensions de <a href=\"https:\/\/whc.ca\/noms-de-domaine\/recherche\" rel=\"nofollow\">noms de domaines<\/a><\/li><li>DNS Anycast, Cr\u00e9ateurs web, Marketing par courriel, SSL et plus!<\/li><li>Assistance experte 24\/7 par t\u00e9l\u00e9phone, clavardage et courriel<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">WHC est un registraire agr\u00e9\u00e9 par l\u2019Autorit\u00e9 Canadienne des Enregistrements Internet (ACEI), un partenaire officiel de cPanel, CloudLinux et SpamExperts et se classe r\u00e9guli\u00e8rement comme le <a href=\"https:\/\/whc.ca\/noms-de-domaine\/recherche\" rel=\"nofollow\">fournisseur de domaines #1<\/a> par le registre des domaines .CA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes fiers d\u2019encourager les initiatives communautaires de WordPress en tant que commanditaires Or \u00e0 l\u2019\u00e9v\u00e8nement WordCamp de Montr\u00e9al. Venez nous voir \u00e0 notre kiosque pour une d\u00e9monstration de nos solutions, pour parler \u00e0 un expert, ou simplement pour dire bonjour!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vous attendons en grand nombre \u00e0 WordCamp Montr\u00e9al 2019!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e9bergement Web Canada (WHC) est une soci\u00e9t\u00e9 de technologie bas\u00e9e \u00e0 Montr\u00e9al. Nous sommes une \u00e9quipe de professionnels du web, travaillant ensemble pour aider les petites entreprises canadiennes \u00e0 s\u2019\u00e9tablir et \u00e0 r\u00e9ussir en ligne. Avec plus de 30 000 clients actifs, WHC est l\u2019une des entreprises web avec la plus forte croissance au Canada. &hellip; <a href=\"https:\/\/montreal.wordcamp.org\/2019-fr\/sponsor\/hebergement-web-canada\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">H\u00e9bergement Web Canada<\/span><\/a><\/p>\n","protected":false},"featured_media":2768,"template":"","meta":{"_crdt_document":"","_wcpt_sponsor_website":"","footnotes":""},"sponsor_level":[4326],"class_list":["post-2767","wcb_sponsor","type-wcb_sponsor","status-publish","has-post-thumbnail","hentry","wcb_sponsor_level-or"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/sponsors\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/sponsors"}],"about":[{"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/types\/wcb_sponsor"}],"version-history":[{"count":1,"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/sponsors\/2767\/revisions"}],"predecessor-version":[{"id":2769,"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/sponsors\/2767\/revisions\/2769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/media\/2768"}],"wp:attachment":[{"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"wcb_sponsor_level","embeddable":true,"href":"https:\/\/montreal.wordcamp.org\/2019-fr\/wp-json\/wp\/v2\/sponsor_level?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}